{"id":7001,"date":"2023-09-02T15:18:08","date_gmt":"2023-09-02T13:18:08","guid":{"rendered":"https:\/\/jockyart.de\/?p=7001"},"modified":"2024-12-22T20:31:48","modified_gmt":"2024-12-22T19:31:48","slug":"50-todestag-von-j-r-r-tolkien","status":"publish","type":"post","link":"https:\/\/jockyart.de\/en\/50-todestag-von-j-r-r-tolkien\/","title":{"rendered":"50. Todestag von J.R.R. Tolkien"},"content":{"rendered":"<p>\u00a9 1991 by JockyArt<\/p>\n\n\n\n<p>Heute vor 50 Jahren starb einer der gro\u00dfartigsten Schriftsteller des letzten Jahrhunderts: J.R.R. Tolkien. Er ist vor allem f\u00fcr seine beiden Hauptwerke &#8222;Der Herr der Ringe&#8220; und &#8222;Der Hobbit&#8220; bekannt. Er hat eine komplette Welt mit eigener Geschichte, Mythologie, V\u00f6lkern und Sprachen erfunden, die sehr komplex ist.<\/p>\n\n\n\n<p>Viele seiner Schriftst\u00fccke wurden erst nach seinem Tod von seinem Sohn Christopher u.a. im &#8222;Silmarillion&#8220; ver\u00f6ffentlicht. Zeit seines Lebens hat es der Autor nicht geschafft, eine einheitliche Geschichte zu ver\u00f6ffentlichen und so hat sein Sohn immer wieder versucht, die Bruchst\u00fccke und unterschiedlichen Versionen der Geschichten, die sich teilweise in Stil und Form unterscheiden, in Buchform zu ver\u00f6ffentlichen.<\/p>\n\n\n\n<p>Was viele nicht wissen, dass J.R.R. Tolkien gl\u00e4ubiger Katholik war, was wenn man einen Blick daf\u00fcr hat, auch in seinen Werken immer wieder zu sehen ist. Als christllicher Tolkienfan sitzt man hier oft zwischen den St\u00fchlen. Auf der einen Seite die Christen, die ein okkultes Werk vermuten und davor warnen. Auf der anderen Seite die Tolkienfans, die die christliche Bez\u00fcge leugnen, weil sich Tolkien ja gegen Allegorien ausgesprochen hat.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"335\" src=\"https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/hobbit03.jpg?resize=980%2C335&#038;ssl=1\" alt=\"\" class=\"wp-image-7006\" srcset=\"https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/hobbit03.jpg?resize=1024%2C350&amp;ssl=1 1024w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/hobbit03.jpg?resize=18%2C6&amp;ssl=1 18w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/hobbit03.jpg?resize=324%2C111&amp;ssl=1 324w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/hobbit03.jpg?resize=416%2C142&amp;ssl=1 416w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/hobbit03.jpg?resize=300%2C102&amp;ssl=1 300w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/hobbit03.jpg?resize=768%2C262&amp;ssl=1 768w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/hobbit03.jpg?w=1060&amp;ssl=1 1060w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><figcaption class=\"wp-element-caption\">Der Hobbit: Mein eigener Versuch, den Roman zu adaptieren &#8211; \u00a9 1991 by JockyArt<\/figcaption><\/figure>\n\n\n\n<!--more-->\n\n\n\n<p>Tolkien war ma\u00dfgeblich daran beteiligt, dass C.S. Lewis zum Glauben gefunden hat. Beide waren gro\u00dfe Liebhaber von Mythen und Sagen. Der entscheidende Punkt, der Lewis Jesus finden lie\u00df, war der Gedanke dass der Mythos vom sterbenden Gott, der wieder aufersteht, in Jesus seine Wahrheit und Ursprung hat. Auch wenn Tolkien mit seinem Werk niemanden aufdr\u00fccken wollte, wie er es zu verstehen hat, sind die christlichen Bez\u00fcge mehr als deutlich.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"150\" src=\"https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/m_gandalf.png?resize=200%2C150&#038;ssl=1\" alt=\"Gandalf\" class=\"wp-image-7004\" srcset=\"https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/m_gandalf.png?w=200&amp;ssl=1 200w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/m_gandalf.png?resize=16%2C12&amp;ssl=1 16w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><figcaption class=\"wp-element-caption\">\u00a9 New Line Cinema\/ Warner Bros.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-left\">Auf meiner eigenen \u25ba <a rel=\"noreferrer noopener\" href=\"http:\/\/derherrderringe.de\/\" data-type=\"link\" data-id=\"http:\/\/derherrderringe.de\/\" target=\"_blank\">Herr der Ringe Fanpage<\/a> habe ich einmal beispielhaft, die \u25ba <a rel=\"noreferrer noopener\" href=\"http:\/\/derherrderringe.de\/gemischtes\/messiasfiguren.htm\" target=\"_blank\">Messiasfiguren<\/a> herausgearbeitet, die sich in dem gro\u00dfartigen Roman finden. Ganz besonders deutlich wird es bei Gandalf, der in Moria sein Leben l\u00e4sst und dann als der wei\u00dfe Reiter wiederkehrt. &#8222;Morija&#8220; ist der Berg, auf dem Abraham seinen Sohn Isaak opfern sollte. Ein prophetischer Hinweis auf den Kreuzestod von Jesus. Auf diesem Berg befand sich Golgatha, die Hinrichtungsst\u00e4tte in Jerusalem. Der <em>wei\u00dfe Reiter<\/em> ist eine Figur in der Offenbarung des Johannes, der den wiederkehrenden Messias beschreibt. Mehr dazu in meinem Artikel: \u25ba <a rel=\"noreferrer noopener\" href=\"http:\/\/derherrderringe.de\/gemischtes\/messiasfiguren.htm\" data-type=\"link\" data-id=\"http:\/\/derherrderringe.de\/gemischtes\/messiasfiguren.htm\" target=\"_blank\">click<\/a>.<\/p>\n\n\n\n<p>Ich habe vor etlichen Jahren selbst mal mit einem Freund zusammen versucht, den &#8222;Hobbit&#8220; als Comic herauszubringen. Ich habe das Projekt aufgegeben als ich bemerkt habe, dass es bereits eine solche Adaption gibt.<\/p>\n\n\n\n<p>Daf\u00fcr habe ich dann Jahre sp\u00e4ter eine Parodie der Verfilmung von Peter Jackson produziert kurz bevor der zweite Teil ins Kino kam. Hier k\u00f6nnt ihr meine Animation sehen, die ich komplett selbst gezeichnet und animiert habe &#8211; mit Hilfe von einigen Freunden: \u25ba <a href=\"https:\/\/youtu.be\/FsOnA41ZaFg?si=OMte47i0XZsibHu1\" data-type=\"link\" data-id=\"https:\/\/youtu.be\/FsOnA41ZaFg?si=OMte47i0XZsibHu1\" target=\"_blank\" rel=\"noreferrer noopener\">The Return of the Ring &#8211; The book of lost scenes<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/youtu.be\/FsOnA41ZaFg?si=Ek74pebS_XrC6snG\" target=\"_blank\" rel=\"noreferrer noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"551\" src=\"https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/Thumb_RotR.jpg?resize=980%2C551&#038;ssl=1\" alt=\"\" class=\"wp-image-7005\" srcset=\"https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/Thumb_RotR.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/Thumb_RotR.jpg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/Thumb_RotR.jpg?resize=18%2C10&amp;ssl=1 18w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/Thumb_RotR.jpg?resize=1320%2C743&amp;ssl=1 1320w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/Thumb_RotR.jpg?resize=324%2C182&amp;ssl=1 324w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/Thumb_RotR.jpg?resize=416%2C234&amp;ssl=1 416w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/Thumb_RotR.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/Thumb_RotR.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/Thumb_RotR.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/a><figcaption class=\"wp-element-caption\">Klicke auf das Bild, um das Video auf YouTube anzuschauen.<\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>\u00a9 1991 by JockyArt Heute vor 50 Jahren starb einer der gro\u00dfartigsten Schriftsteller des letzten Jahrhunderts: J.R.R. Tolkien. Er ist vor allem f\u00fcr seine beiden Hauptwerke &#8222;Der Herr der Ringe&#8220; und &#8222;Der Hobbit&#8220; bekannt. Er hat eine komplette Welt mit eigener Geschichte, Mythologie, V\u00f6lkern und Sprachen erfunden, die sehr komplex ist. Viele seiner Schriftst\u00fccke wurden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1015],"tags":[1010,1013,1007,1009,1008],"class_list":["post-7001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spezial","tag-glaeubig","tag-herr-der-ringe","tag-j-r-r-tolkien","tag-katholik","tag-todestag"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/jockyart.de\/wp-content\/uploads\/2023\/09\/comic_bilbo.jpg?fit=1300%2C2141&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/jockyart.de\/en\/wp-json\/wp\/v2\/posts\/7001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jockyart.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jockyart.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jockyart.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jockyart.de\/en\/wp-json\/wp\/v2\/comments?post=7001"}],"version-history":[{"count":6,"href":"https:\/\/jockyart.de\/en\/wp-json\/wp\/v2\/posts\/7001\/revisions"}],"predecessor-version":[{"id":9574,"href":"https:\/\/jockyart.de\/en\/wp-json\/wp\/v2\/posts\/7001\/revisions\/9574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jockyart.de\/en\/wp-json\/wp\/v2\/media\/7003"}],"wp:attachment":[{"href":"https:\/\/jockyart.de\/en\/wp-json\/wp\/v2\/media?parent=7001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jockyart.de\/en\/wp-json\/wp\/v2\/categories?post=7001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jockyart.de\/en\/wp-json\/wp\/v2\/tags?post=7001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}